{"id":14,"date":"2020-10-29T12:55:34","date_gmt":"2020-10-29T12:55:34","guid":{"rendered":"https:\/\/www.agenciadosmasdos.com\/index.php\/about-us\/"},"modified":"2023-07-31T21:57:18","modified_gmt":"2023-07-31T21:57:18","slug":"quienes-somos","status":"publish","type":"page","link":"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/","title":{"rendered":"Qui\u00e9nes Somos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"14\" class=\"elementor elementor-14\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-371e341 elementor-section-height-min-height elementor-section-items-bottom elementor-section-content-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"371e341\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-007f03a\" data-id=\"007f03a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4086b8e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4086b8e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-17048ea\" data-id=\"17048ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56886c0 elementor-widget elementor-widget-heading\" data-id=\"56886c0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Con\u00f3zcanos<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44f99fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44f99fe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e2a398e\" data-id=\"e2a398e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a5f665 elementor-widget elementor-widget-heading\" data-id=\"8a5f665\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">01<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8da031c elementor-widget elementor-widget-heading\" data-id=\"8da031c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Qui\u00e9nes Somos<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4207888\" data-id=\"4207888\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6c128f elementor-widget elementor-widget-heading\" data-id=\"b6c128f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Porqu\u00e9 <br>Dos m\u00e1s Dos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58a2c21 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58a2c21\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72c3c00\" data-id=\"72c3c00\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ae44670 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae44670\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-51c7cd1\" data-id=\"51c7cd1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-049669f elementor-widget elementor-widget-heading\" data-id=\"049669f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">El origen de Dos m\u00e1s Dos surgi\u00f3 de una conversaci\u00f3n entre dos amigas y colegas en la que se discut\u00eda si la suma de 2+2 es mayor que 4.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-63c3aa6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63c3aa6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f976173\" data-id=\"f976173\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5c77c9 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d5c77c9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">A partir de esta conversaci\u00f3n, surgi\u00f3 la idea de buscar a dos profesionales m\u00e1s, lo que result\u00f3 en la incorporaci\u00f3n de muchas ideas y talento. Estas ideas, aunque parecen simples, no eran evidentes para nosotras en un principio, pero al trabajar en equipo, logramos darles forma. Se caracterizan por ser fuera de lo com\u00fan, provocativas y creativas, y se diferencian de las ideas convencionales mediante enfoques estrat\u00e9gicos.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-30658a3\" data-id=\"30658a3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-973550e elementor-widget elementor-widget-text-editor\" data-id=\"973550e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">En resumen, la premisa de Dos m\u00e1s Dos es que cuatro mentes siempre ser\u00e1n mejores que una sola, lo que implica que trabajar en equipo y combinar diferentes perspectivas y habilidades resultar\u00e1 en mejores resultados que trabajar de forma individual.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e8df4c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e8df4c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9021372\" data-id=\"9021372\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f29bf23 elementor-widget elementor-widget-heading\" data-id=\"f29bf23\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">02<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ed9ffd elementor-widget elementor-widget-heading\" data-id=\"8ed9ffd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Nuestra gente<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b1f6799\" data-id=\"b1f6799\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5a9291 elementor-widget elementor-widget-heading\" data-id=\"b5a9291\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Equipo L\u00edder<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12bd395 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12bd395\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cb3011a\" data-id=\"cb3011a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7479ef5\" data-id=\"7479ef5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bb57ec0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb57ec0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-349bc5f\" data-id=\"349bc5f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0143a9 elementor-widget elementor-widget-image\" data-id=\"b0143a9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/marce.jpg\" class=\"attachment-full size-full wp-image-378\" alt=\"\" srcset=\"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/marce.jpg 320w, https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/marce-300x300.jpg 300w, https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/marce-150x150.jpg 150w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-061f3a5 elementor-widget elementor-widget-heading\" data-id=\"061f3a5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><span>Marcela <\/span><br><span>Marqu\u00e9s<\/span><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2e422b elementor-widget elementor-widget-text-editor\" data-id=\"f2e422b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Social, din\u00e1mica y proactiva. Apasionada por la organizaci\u00f3n de eventos, estructurada pero libre. Su formaci\u00f3n profesional de comunicadora le permite resolver de con agilidad los retos diarios.<\/p><p>Experiencia en la creaci\u00f3n e implementaci\u00f3n de actividades nacionales e internacionales as\u00ed como un amplio expertise en el desarrollo de estrategias para empresas\u00a0familiares.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5328adb\" data-id=\"5328adb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0381f01 elementor-widget elementor-widget-image\" data-id=\"0381f01\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/erika.jpg\" class=\"attachment-full size-full wp-image-376\" alt=\"\" srcset=\"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/erika.jpg 320w, https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/erika-300x300.jpg 300w, https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/erika-150x150.jpg 150w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4eb17e3 elementor-widget elementor-widget-heading\" data-id=\"4eb17e3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">Erika Vega<br>Palavicini<\/span><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfc573e elementor-widget elementor-widget-text-editor\" data-id=\"dfc573e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"_04xlpA direction-ltr align-start para-style-body\"><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">Creativa y perspicaz para la generaci\u00f3n de ideas. Siempre buscando la transformaci\u00f3n de situaciones dif\u00edciles o negativas para beneficio de las personas involucradas.<\/span><\/p><p class=\"_04xlpA direction-ltr align-start para-style-body\"><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">Es comunicadora de profesi\u00f3n con amplia experiencia en gesti\u00f3n de proyectos especialmente en el \u00e1rea de la salud, pionera en el campo del Advocacy en Costa Rica y experta en manejo de Organizaciones No Gubernamentales.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6092985\" data-id=\"6092985\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80db253 elementor-widget elementor-widget-image\" data-id=\"80db253\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/fanny.jpg\" class=\"attachment-full size-full wp-image-377\" alt=\"\" srcset=\"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/fanny.jpg 320w, https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/fanny-300x300.jpg 300w, https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/fanny-150x150.jpg 150w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cda4aaf elementor-widget elementor-widget-heading\" data-id=\"cda4aaf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Fanny<br>Gamboa<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba6f3e4 elementor-widget elementor-widget-text-editor\" data-id=\"ba6f3e4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dise\u00f1adora industrial y gr\u00e1fica con 25 a\u00f1os de experiencia en herramientas digitales y comunicaci\u00f3n visual, le han permitido crear soluciones para los desaf\u00edos de los clientes.<\/p><p>Por los contantes cambios en esta \u00e1rea, gracias a la capacitaci\u00f3n en nuevas tendencias y herramientas, ha logrado integrar el dise\u00f1o con la tecnolog\u00eda, eventos y la comunicaci\u00f3n, generando soluciones efectivas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e19c521\" data-id=\"e19c521\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbe5bf9 elementor-widget elementor-widget-image\" data-id=\"cbe5bf9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/carli.jpg\" class=\"attachment-full size-full wp-image-375\" alt=\"\" srcset=\"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/carli.jpg 320w, https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/carli-300x300.jpg 300w, https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/carli-150x150.jpg 150w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd35055 elementor-widget elementor-widget-heading\" data-id=\"fd35055\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><span>Carlina<\/span><br><span>Alfaro<\/span><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c2d6f3 elementor-widget elementor-widget-text-editor\" data-id=\"8c2d6f3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Pr\u00e1ctica, creativa, siempre en busca de la mejor idea y resolutiva.<\/span><\/p><p><span style=\"font-weight: 400;\">Posee una visi\u00f3n 360 de su oficio, ya que trabaj\u00f3 en agencias de comunicaci\u00f3n, en instituciones p\u00fablicas de gobierno, sector privado, transnacionales y en los \u00faltimos a\u00f1os como consultora independiente.<\/span><\/p><p><span style=\"font-weight: 400;\">Es especialista en gesti\u00f3n de prensa, relaciones p\u00fablicas y comunicaci\u00f3n pol\u00edtica.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9929c37 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9929c37\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-65ea946\" data-id=\"65ea946\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7dd393e elementor-widget elementor-widget-heading\" data-id=\"7dd393e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">03<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1c2623 elementor-widget elementor-widget-heading\" data-id=\"d1c2623\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Nuestros aliados<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-40ade17\" data-id=\"40ade17\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b273052 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b273052\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ce8e127\" data-id=\"ce8e127\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af9fb6f elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"af9fb6f\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-video\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tJes\u00fas Fung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tProductor Audiovisual\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7887bfd\" data-id=\"7887bfd\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b004a9 elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"1b004a9\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-photo-video\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMayela L\u00f3pez\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tFot\u00f3grafa y periodista\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bdcebcb\" data-id=\"bdcebcb\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-475d28f elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"475d28f\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-project-diagram\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tVera Farah \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDirectora de Proyectos\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-20f1d36 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20f1d36\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0875e47\" data-id=\"0875e47\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8708a1f\" data-id=\"8708a1f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d5df8f elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"8d5df8f\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-code-branch\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAaron Barrantes\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tArquitectura tecnol\u00f3gica\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-76bdf8f\" data-id=\"76bdf8f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Con\u00f3zcanos 01 Qui\u00e9nes Somos Porqu\u00e9 Dos m\u00e1s Dos El origen de Dos m\u00e1s Dos surgi\u00f3 de una conversaci\u00f3n entre dos amigas y colegas en la que se discut\u00eda si la suma de 2+2 es mayor que 4. A partir de esta conversaci\u00f3n, surgi\u00f3 la idea de buscar a dos profesionales m\u00e1s, lo que result\u00f3 en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"disabled","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-14","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qui\u00e9nes Somos - Agencia Dos Mas DOS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qui\u00e9nes Somos - Agencia Dos Mas DOS\" \/>\n<meta property=\"og:description\" content=\"Con\u00f3zcanos 01 Qui\u00e9nes Somos Porqu\u00e9 Dos m\u00e1s Dos El origen de Dos m\u00e1s Dos surgi\u00f3 de una conversaci\u00f3n entre dos amigas y colegas en la que se discut\u00eda si la suma de 2+2 es mayor que 4. A partir de esta conversaci\u00f3n, surgi\u00f3 la idea de buscar a dos profesionales m\u00e1s, lo que result\u00f3 en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/\" \/>\n<meta property=\"og:site_name\" content=\"Agencia Dos Mas DOS\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-31T21:57:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/marce.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/\",\"url\":\"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/\",\"name\":\"Qui\u00e9nes Somos - Agencia Dos Mas DOS\",\"isPartOf\":{\"@id\":\"https:\/\/agenciadosmasdos.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/marce.jpg\",\"datePublished\":\"2020-10-29T12:55:34+00:00\",\"dateModified\":\"2023-07-31T21:57:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/#breadcrumb\"},\"inLanguage\":\"es-CR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CR\",\"@id\":\"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/#primaryimage\",\"url\":\"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/marce.jpg\",\"contentUrl\":\"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/marce.jpg\",\"width\":320,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agenciadosmasdos.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qui\u00e9nes Somos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agenciadosmasdos.com\/#website\",\"url\":\"https:\/\/agenciadosmasdos.com\/\",\"name\":\"Agencia Dos Mas DOS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/agenciadosmasdos.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agenciadosmasdos.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agenciadosmasdos.com\/#organization\",\"name\":\"Agencia Dos Mas DOS\",\"url\":\"https:\/\/agenciadosmasdos.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CR\",\"@id\":\"https:\/\/agenciadosmasdos.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-itemAsset-3.png\",\"contentUrl\":\"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-itemAsset-3.png\",\"width\":531,\"height\":177,\"caption\":\"Agencia Dos Mas DOS\"},\"image\":{\"@id\":\"https:\/\/agenciadosmasdos.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qui\u00e9nes Somos - Agencia Dos Mas DOS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/","og_locale":"es_ES","og_type":"article","og_title":"Qui\u00e9nes Somos - Agencia Dos Mas DOS","og_description":"Con\u00f3zcanos 01 Qui\u00e9nes Somos Porqu\u00e9 Dos m\u00e1s Dos El origen de Dos m\u00e1s Dos surgi\u00f3 de una conversaci\u00f3n entre dos amigas y colegas en la que se discut\u00eda si la suma de 2+2 es mayor que 4. A partir de esta conversaci\u00f3n, surgi\u00f3 la idea de buscar a dos profesionales m\u00e1s, lo que result\u00f3 en [&hellip;]","og_url":"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/","og_site_name":"Agencia Dos Mas DOS","article_modified_time":"2023-07-31T21:57:18+00:00","og_image":[{"url":"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/marce.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/","url":"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/","name":"Qui\u00e9nes Somos - Agencia Dos Mas DOS","isPartOf":{"@id":"https:\/\/agenciadosmasdos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/#primaryimage"},"image":{"@id":"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/#primaryimage"},"thumbnailUrl":"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/marce.jpg","datePublished":"2020-10-29T12:55:34+00:00","dateModified":"2023-07-31T21:57:18+00:00","breadcrumb":{"@id":"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/#breadcrumb"},"inLanguage":"es-CR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/"]}]},{"@type":"ImageObject","inLanguage":"es-CR","@id":"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/#primaryimage","url":"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/marce.jpg","contentUrl":"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/marce.jpg","width":320,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/agenciadosmasdos.com\/index.php\/quienes-somos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agenciadosmasdos.com\/"},{"@type":"ListItem","position":2,"name":"Qui\u00e9nes Somos"}]},{"@type":"WebSite","@id":"https:\/\/agenciadosmasdos.com\/#website","url":"https:\/\/agenciadosmasdos.com\/","name":"Agencia Dos Mas DOS","description":"","publisher":{"@id":"https:\/\/agenciadosmasdos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agenciadosmasdos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CR"},{"@type":"Organization","@id":"https:\/\/agenciadosmasdos.com\/#organization","name":"Agencia Dos Mas DOS","url":"https:\/\/agenciadosmasdos.com\/","logo":{"@type":"ImageObject","inLanguage":"es-CR","@id":"https:\/\/agenciadosmasdos.com\/#\/schema\/logo\/image\/","url":"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-itemAsset-3.png","contentUrl":"https:\/\/agenciadosmasdos.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-itemAsset-3.png","width":531,"height":177,"caption":"Agencia Dos Mas DOS"},"image":{"@id":"https:\/\/agenciadosmasdos.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/agenciadosmasdos.com\/index.php\/wp-json\/wp\/v2\/pages\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agenciadosmasdos.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/agenciadosmasdos.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/agenciadosmasdos.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agenciadosmasdos.com\/index.php\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":29,"href":"https:\/\/agenciadosmasdos.com\/index.php\/wp-json\/wp\/v2\/pages\/14\/revisions"}],"predecessor-version":[{"id":543,"href":"https:\/\/agenciadosmasdos.com\/index.php\/wp-json\/wp\/v2\/pages\/14\/revisions\/543"}],"wp:attachment":[{"href":"https:\/\/agenciadosmasdos.com\/index.php\/wp-json\/wp\/v2\/media?parent=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}